{"id":893,"date":"2019-07-31T13:04:03","date_gmt":"2019-07-31T13:04:03","guid":{"rendered":"https:\/\/fornoscontenidors.com\/convocatoria-dajuts-per-a-la-retirada-de-residus-que-continguin-amiant\/"},"modified":"2019-07-31T13:14:36","modified_gmt":"2019-07-31T13:14:36","slug":"convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto","status":"publish","type":"post","link":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/","title":{"rendered":"Convocatoria de ayudas para la retirada de residuos que contengan amianto"},"content":{"rendered":"<p>Con el objetivo de minimizar el riesgo que comporta el <strong>amianto<\/strong> para la salud p\u00fablica y obtener una mejora ambiental, la Ag\u00e8ncia de Residus de Catalunya ha abierto la convocatoria de ayudas para la <strong>retirada de residuos de materiales de aislamiento y de la construcci\u00f3n que contengan este material<\/strong>.<\/p>\n<p>Realizar una correcta <strong>gesti\u00f3n del amianto<\/strong> es fundamental porque es un material perjudicial para la salud. A pesar de que hay la creencia de que los elementos de fibrocemento solo son perjudiciales para la salud cuando se rompen, la realidad es que la exposici\u00f3n constante tiene consecuencias, puesto que el paso de los a\u00f1os deteriora notablemente estos materiales.<\/p>\n<p>Por este motivo, y para fomentar y procurar que todo el proceso de<strong> gesti\u00f3n del amianto<\/strong> se realice con las \u00f3ptimas condiciones ambientales, la Ag\u00e8ncia de Residus de Catalunya ha abierto esta subvenci\u00f3n.<\/p>\n<h3>\u00bfQui\u00e9n se puede beneficiar de las subvenciones?<\/h3>\n<p>Pueden acogerse a las <strong>ayudas para la retirada de residuos con amianto<\/strong> los propietarios de bienes inmuebles que contengan elementos de amianto procedentes de la construcci\u00f3n, sean personas f\u00edsicas o jur\u00eddicas, p\u00fablicas o privadas, y comunidades de vecinos.<\/p>\n<h3>Plazo para presentar las solicitudes<\/h3>\n<p>La partida presupuestaria es de 1 mill\u00f3n de euros y el plazo de presentaci\u00f3n es hasta la finalizaci\u00f3n de la disponibilidad presupuestaria o bien hasta el 29 de noviembre de 2019.<\/p>\n<p>Adem\u00e1s, las subvenciones cubren el 100% de la factura emitida por la empresa RERA, con una cantidad m\u00e1xima de 6000 \u20ac.<\/p>\n<h3>Requisitos para solicitar la subvenci\u00f3n<\/h3>\n<p>La subvenci\u00f3n cubre los gastos de desamiantado, el transporte y la gesti\u00f3n de los residuos, realizados a partir de la presentaci\u00f3n de la solicitud, pero solo una<strong> empresa especializada e inscrita en el RERA<\/strong> (Registro de Empresas para la Retirada de Amianto) puede realizar este proceso de desamiantado.<\/p>\n<p>De este modo, es indispensable que una empresa especializada gestione la documentaci\u00f3n de control y seguimiento necesaria seg\u00fan la normativa.<\/p>\n<p>Desde Forn\u00f3s Contenidors, como empresa inscrita al RERA y con una larga experiencia en el sector, te podemos ofrecer un acompa\u00f1amiento completo durante todo el proceso: desde la creaci\u00f3n de la solicitud y hasta la <strong>gesti\u00f3n y transporte de los residuos con amianto<\/strong>.<\/p>\n<p>Durante este proceso, aportaremos la documentaci\u00f3n necesaria y te explicaremos en todo momento los pasos que se tienen que realizar. Adem\u00e1s, en el momento del desamiantado, garantizamos su ejecuci\u00f3n siguiendo los sistemas de seguridad y tomando las medidas necesarias de protecci\u00f3n.<\/p>\n<p>Ante cualquier duda relacionada con la <strong>convocatoria de ayudas para la retirada de residuos que contengan amianto<\/strong>, no dudes en contactar con nosotros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de minimizar el riesgo que comporta el amianto para la salud p\u00fablica y obtener una mejora ambiental, la Ag\u00e8ncia de Residus de Catalunya ha abierto la convocatoria de ayudas para la retirada de residuos de materiales de aislamiento y de la construcci\u00f3n que contengan este material. Realizar una correcta gesti\u00f3n del amianto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"categories":[7],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Convocatoria de ayudas para la retirada de residuos que contengan amianto - Fornos Contenidors<\/title>\n<meta name=\"description\" content=\"Tota la informaci\u00f3n sobre la convocatoria de ayudas para la retirada de residuos de materiales de aislamiento y construcci\u00f3n que contengan amianto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocatoria de ayudas para la retirada de residuos que contengan amianto - Fornos Contenidors\" \/>\n<meta property=\"og:description\" content=\"Tota la informaci\u00f3n sobre la convocatoria de ayudas para la retirada de residuos de materiales de aislamiento y construcci\u00f3n que contengan amianto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/\" \/>\n<meta property=\"og:site_name\" content=\"Fornos Contenidors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FornosContenidorsSL\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-31T13:04:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-31T13:14:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2019\/07\/Fornos_Banner_15-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"infotic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/fornoscontenidors.com\/es\/#organization\",\"name\":\"Fornos Contenidors\",\"url\":\"https:\/\/fornoscontenidors.com\/es\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/FornosContenidorsSL\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fornoscontenidors.com\/es\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2018\/11\/Fornos_Logo_2T_2018.svg\",\"contentUrl\":\"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2018\/11\/Fornos_Logo_2T_2018.svg\",\"caption\":\"Fornos Contenidors\"},\"image\":{\"@id\":\"https:\/\/fornoscontenidors.com\/es\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fornoscontenidors.com\/es\/#website\",\"url\":\"https:\/\/fornoscontenidors.com\/es\/\",\"name\":\"Fornos Contenidors\",\"description\":\"Lloguer de contenidors al Baix Ebre\",\"publisher\":{\"@id\":\"https:\/\/fornoscontenidors.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fornoscontenidors.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2019\/07\/Fornos_Banner_15-1.jpg\",\"contentUrl\":\"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2019\/07\/Fornos_Banner_15-1.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#webpage\",\"url\":\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/\",\"name\":\"Convocatoria de ayudas para la retirada de residuos que contengan amianto - Fornos Contenidors\",\"isPartOf\":{\"@id\":\"https:\/\/fornoscontenidors.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#primaryimage\"},\"datePublished\":\"2019-07-31T13:04:03+00:00\",\"dateModified\":\"2019-07-31T13:14:36+00:00\",\"description\":\"Tota la informaci\\u00f3n sobre la convocatoria de ayudas para la retirada de residuos de materiales de aislamiento y construcci\\u00f3n que contengan amianto.\",\"breadcrumb\":{\"@id\":\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/fornoscontenidors.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocatoria de ayudas para la retirada de residuos que contengan amianto\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#webpage\"},\"author\":{\"@id\":\"https:\/\/fornoscontenidors.com\/es\/#\/schema\/person\/fde62a877cf0ef0dd262555cbc7fa3a4\"},\"headline\":\"Convocatoria de ayudas para la retirada de residuos que contengan amianto\",\"datePublished\":\"2019-07-31T13:04:03+00:00\",\"dateModified\":\"2019-07-31T13:14:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#webpage\"},\"wordCount\":460,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/fornoscontenidors.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2019\/07\/Fornos_Banner_15-1.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/fornoscontenidors.com\/es\/#\/schema\/person\/fde62a877cf0ef0dd262555cbc7fa3a4\",\"name\":\"infotic\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/fornoscontenidors.com\/es\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b97dcb01d727e66708d32c9376d856a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b97dcb01d727e66708d32c9376d856a7?s=96&d=mm&r=g\",\"caption\":\"infotic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocatoria de ayudas para la retirada de residuos que contengan amianto - Fornos Contenidors","description":"Tota la informaci\u00f3n sobre la convocatoria de ayudas para la retirada de residuos de materiales de aislamiento y construcci\u00f3n que contengan amianto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/","og_locale":"es_ES","og_type":"article","og_title":"Convocatoria de ayudas para la retirada de residuos que contengan amianto - Fornos Contenidors","og_description":"Tota la informaci\u00f3n sobre la convocatoria de ayudas para la retirada de residuos de materiales de aislamiento y construcci\u00f3n que contengan amianto.","og_url":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/","og_site_name":"Fornos Contenidors","article_publisher":"https:\/\/www.facebook.com\/FornosContenidorsSL","article_published_time":"2019-07-31T13:04:03+00:00","article_modified_time":"2019-07-31T13:14:36+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2019\/07\/Fornos_Banner_15-1.jpg","path":"\/home\/customer\/www\/fornoscontenidors.com\/public_html\/wp-content\/uploads\/2019\/07\/Fornos_Banner_15-1.jpg","size":"full","id":891,"alt":"","pixels":753600,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"infotic","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/fornoscontenidors.com\/es\/#organization","name":"Fornos Contenidors","url":"https:\/\/fornoscontenidors.com\/es\/","sameAs":["https:\/\/www.facebook.com\/FornosContenidorsSL"],"logo":{"@type":"ImageObject","@id":"https:\/\/fornoscontenidors.com\/es\/#logo","inLanguage":"es","url":"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2018\/11\/Fornos_Logo_2T_2018.svg","contentUrl":"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2018\/11\/Fornos_Logo_2T_2018.svg","caption":"Fornos Contenidors"},"image":{"@id":"https:\/\/fornoscontenidors.com\/es\/#logo"}},{"@type":"WebSite","@id":"https:\/\/fornoscontenidors.com\/es\/#website","url":"https:\/\/fornoscontenidors.com\/es\/","name":"Fornos Contenidors","description":"Lloguer de contenidors al Baix Ebre","publisher":{"@id":"https:\/\/fornoscontenidors.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fornoscontenidors.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#primaryimage","inLanguage":"es","url":"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2019\/07\/Fornos_Banner_15-1.jpg","contentUrl":"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2019\/07\/Fornos_Banner_15-1.jpg","width":1200,"height":628},{"@type":"WebPage","@id":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#webpage","url":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/","name":"Convocatoria de ayudas para la retirada de residuos que contengan amianto - Fornos Contenidors","isPartOf":{"@id":"https:\/\/fornoscontenidors.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#primaryimage"},"datePublished":"2019-07-31T13:04:03+00:00","dateModified":"2019-07-31T13:14:36+00:00","description":"Tota la informaci\u00f3n sobre la convocatoria de ayudas para la retirada de residuos de materiales de aislamiento y construcci\u00f3n que contengan amianto.","breadcrumb":{"@id":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fornoscontenidors.com\/es\/"},{"@type":"ListItem","position":2,"name":"Convocatoria de ayudas para la retirada de residuos que contengan amianto"}]},{"@type":"Article","@id":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#article","isPartOf":{"@id":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#webpage"},"author":{"@id":"https:\/\/fornoscontenidors.com\/es\/#\/schema\/person\/fde62a877cf0ef0dd262555cbc7fa3a4"},"headline":"Convocatoria de ayudas para la retirada de residuos que contengan amianto","datePublished":"2019-07-31T13:04:03+00:00","dateModified":"2019-07-31T13:14:36+00:00","mainEntityOfPage":{"@id":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#webpage"},"wordCount":460,"commentCount":0,"publisher":{"@id":"https:\/\/fornoscontenidors.com\/es\/#organization"},"image":{"@id":"https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#primaryimage"},"thumbnailUrl":"https:\/\/fornoscontenidors.com\/wp-content\/uploads\/2019\/07\/Fornos_Banner_15-1.jpg","articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fornoscontenidors.com\/es\/convocatoria-de-ayudas-para-la-retirada-de-residuos-que-contengan-amianto\/#respond"]}]},{"@type":"Person","@id":"https:\/\/fornoscontenidors.com\/es\/#\/schema\/person\/fde62a877cf0ef0dd262555cbc7fa3a4","name":"infotic","image":{"@type":"ImageObject","@id":"https:\/\/fornoscontenidors.com\/es\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/b97dcb01d727e66708d32c9376d856a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b97dcb01d727e66708d32c9376d856a7?s=96&d=mm&r=g","caption":"infotic"}}]}},"_links":{"self":[{"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/posts\/893"}],"collection":[{"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/comments?post=893"}],"version-history":[{"count":3,"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/posts\/893\/revisions"}],"predecessor-version":[{"id":896,"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/posts\/893\/revisions\/896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/media\/891"}],"wp:attachment":[{"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/media?parent=893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/categories?post=893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fornoscontenidors.com\/es\/wp-json\/wp\/v2\/tags?post=893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}